{"id":1295,"date":"2023-03-28T06:21:08","date_gmt":"2023-03-28T06:21:08","guid":{"rendered":"https:\/\/lavocedelpaese.info\/index.php\/2023\/03\/28\/anziani-quali-novita-dalle-politiche-a-loro-favore\/"},"modified":"2023-03-28T06:21:08","modified_gmt":"2023-03-28T06:21:08","slug":"anziani-quali-novita-dalle-politiche-a-loro-favore","status":"publish","type":"post","link":"https:\/\/noicattaro.lavocedelpaese.info\/index.php\/2023\/03\/28\/anziani-quali-novita-dalle-politiche-a-loro-favore\/","title":{"rendered":"Anziani: quali novit\u00e0 dalle politiche a loro favore?"},"content":{"rendered":"<p>\u00a0<\/p>\n<p>\u200b\u00a0<\/p>\n<p>\u200bCassano \u2013 La Voce del Paese\u00a0<\/p>\n<p><strong>Venerdi 31 Marzo ore 18.00 presso la Sala Consiliare del Comune di Cassano delle Murge<\/strong>, Piazza Rossani, il Gruppo Consiliare \u201cCassano Avanti\u201d terr\u00e0 un incontro sul tema \u201cPOLITICHE IN FAVORE DELLE PERSONE ANZIANE\u201d alla luce della approvazione del Disegno di Legge \u00a0che disciplina alcune deleghe al Governo in materia di politiche in favore delle persone anziane come il riconoscimento del\u00a0<em>diritto a determinarsi in maniera indipendente, libera, informata e consapevole con riferimento alle decisioni che riguardano la loro assistenza, nonch\u00e9 alla <\/em><strong>continuit\u00e0 di vita e di cure presso il proprio domicilio.<\/strong><\/p>\n<p>Interverranno il Senatore Ignazio Zullo, componente della commissione \u201cAffari sociali, Sanit\u00e0, Lavoro e Previdenza\u201d, il Dott. Amedeo Venezia Medico geriatra dell\u2019Ospedale Miulli di Acquaviva delle Fonti, la dott.ssa Zecca Assistente Sociale della Residenza per anziani \u201cSan Martino\u201d di Cassano delle Murge ed il dott. Luca Savino dell\u2019Hospice\/Cure Palliative Grumo Appula.<\/p>\n<p>\u201cDal confronto sar\u00e0 importante verificare come cambier\u00e0 l\u2019approccio al tema del sostegno in favore degli anziani anche alla luce dei progetti a valere sui fondi PNRR\u201d, spiega una nota del gruppo consiliare.<\/p>\n<p>La partecipazione \u00e8 libera.<\/p>\n<p><a class=\"a2a_button_facebook\" href=\"https:\/\/www.addtoany.com\/add_to\/facebook?linkurl=https%3A%2F%2Fcassano.lavocedelpaese.info%2Findex.php%2F2023%2F03%2F28%2Fanziani-quali-novita-dalle-politiche-a-loro-favore%2F&amp;linkname=Anziani%3A%20quali%20novit%C3%A0%20dalle%20politiche%20a%20loro%20favore%3F\" title=\"Facebook\" target=\"_blank\" rel=\"noopener\"><\/a><a class=\"a2a_button_twitter\" href=\"https:\/\/www.addtoany.com\/add_to\/twitter?linkurl=https%3A%2F%2Fcassano.lavocedelpaese.info%2Findex.php%2F2023%2F03%2F28%2Fanziani-quali-novita-dalle-politiche-a-loro-favore%2F&amp;linkname=Anziani%3A%20quali%20novit%C3%A0%20dalle%20politiche%20a%20loro%20favore%3F\" title=\"Twitter\" target=\"_blank\" rel=\"noopener\"><\/a><a class=\"a2a_button_whatsapp\" href=\"https:\/\/www.addtoany.com\/add_to\/whatsapp?linkurl=https%3A%2F%2Fcassano.lavocedelpaese.info%2Findex.php%2F2023%2F03%2F28%2Fanziani-quali-novita-dalle-politiche-a-loro-favore%2F&amp;linkname=Anziani%3A%20quali%20novit%C3%A0%20dalle%20politiche%20a%20loro%20favore%3F\" title=\"WhatsApp\" target=\"_blank\" rel=\"noopener\"><\/a><a class=\"a2a_button_telegram\" href=\"https:\/\/www.addtoany.com\/add_to\/telegram?linkurl=https%3A%2F%2Fcassano.lavocedelpaese.info%2Findex.php%2F2023%2F03%2F28%2Fanziani-quali-novita-dalle-politiche-a-loro-favore%2F&amp;linkname=Anziani%3A%20quali%20novit%C3%A0%20dalle%20politiche%20a%20loro%20favore%3F\" title=\"Telegram\" target=\"_blank\" rel=\"noopener\"><\/a><a class=\"a2a_button_email\" href=\"https:\/\/www.addtoany.com\/add_to\/email?linkurl=https%3A%2F%2Fcassano.lavocedelpaese.info%2Findex.php%2F2023%2F03%2F28%2Fanziani-quali-novita-dalle-politiche-a-loro-favore%2F&amp;linkname=Anziani%3A%20quali%20novit%C3%A0%20dalle%20politiche%20a%20loro%20favore%3F\" title=\"Email\" target=\"_blank\" rel=\"noopener\"><\/a><\/p>\n<p>\u00a0<\/p>","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u200b\u00a0 \u200bCassano \u2013 La Voce del Paese\u00a0 Venerdi 31 Marzo ore 18.00 presso la Sala Consiliare del Comune di<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1295","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/noicattaro.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts\/1295","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noicattaro.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noicattaro.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noicattaro.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/comments?post=1295"}],"version-history":[{"count":0,"href":"https:\/\/noicattaro.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts\/1295\/revisions"}],"wp:attachment":[{"href":"https:\/\/noicattaro.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/media?parent=1295"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noicattaro.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/categories?post=1295"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noicattaro.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/tags?post=1295"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}