{"id":1846,"date":"2023-08-07T06:32:16","date_gmt":"2023-08-07T06:32:16","guid":{"rendered":"https:\/\/lavocedelpaese.info\/index.php\/2023\/08\/07\/cinema-in-piazza-con-book-club-il-9-agosto\/"},"modified":"2023-08-07T06:32:16","modified_gmt":"2023-08-07T06:32:16","slug":"cinema-in-piazza-con-book-club-il-9-agosto","status":"publish","type":"post","link":"https:\/\/noicattaro.lavocedelpaese.info\/index.php\/2023\/08\/07\/cinema-in-piazza-con-book-club-il-9-agosto\/","title":{"rendered":"Cinema in piazza con \u201cBook Club\u201d il 9 agosto"},"content":{"rendered":"<p>\u00a0<\/p>\n<p>\u200b\u00a0<\/p>\n<p>\u200bCassano \u2013 La Voce del Paese\u00a0<\/p>\n<p>Torna il cinema in piazza, per due serate, a Cassano delle Murge.<\/p>\n<p><strong>Il 9 ed il 23 agosto, alle ore 21.00 in piazza Moro<\/strong> (ingresso gratuito), saranno proiettati rispettivamente: \u201cBook Club \u2013 tutto pu\u00f2 succedere\u201d e \u201cCorro da te\u201d, film italiano del 2022 diretto da Riccardo Milani, remake della pellicola cinematografica francese Tutti in piedi (Tout le monde debout).<\/p>\n<p>L\u2019organizzazione \u00e8 a cura dell\u2019Associazione \u201cApulia Country Pro Loco\u201d nell\u2019ambito del cartellone dell\u2019Estate Cassanese promossa dall\u2019Amministrazione Comunale.<\/p>\n<p class=\"has-text-align-center\"><strong>\u201cBook Club \u2013 tutto pu\u00f2 succedere\u201d<\/strong><\/p>\n<p><strong><em>La trama.<\/em><\/strong><\/p>\n<p>Quattro donne, che da trent\u2019anni si incontrano ogni mese per commentare la lettura di un libro, scoprono il libro \u201cCinquanta sfumature di grigio\u201d. Decidono cos\u00ec di sfruttare il romanzo per \u201cmovimentare\u201d la loro vita\u2026<\/p>\n<p><strong><em>Il cast<\/em><\/strong><\/p>\n<p>Regia: Bill Holderman<\/p>\n<p>Attori: Jane Fonda, Alicia Silverstone, Mary Steenburgen, Diane Keaton, Andy Garcia, Candice Bergen<\/p>\n<p><a class=\"a2a_button_facebook\" href=\"https:\/\/www.addtoany.com\/add_to\/facebook?linkurl=https%3A%2F%2Fcassano.lavocedelpaese.info%2Findex.php%2F2023%2F08%2F07%2Fcinema-in-piazza-con-book-club-il-9-agosto%2F&amp;linkname=Cinema%20in%20piazza%20con%20%E2%80%9CBook%20Club%E2%80%9D%20il%209%20agosto\" title=\"Facebook\" target=\"_blank\" rel=\"noopener\"><\/a><a class=\"a2a_button_twitter\" href=\"https:\/\/www.addtoany.com\/add_to\/twitter?linkurl=https%3A%2F%2Fcassano.lavocedelpaese.info%2Findex.php%2F2023%2F08%2F07%2Fcinema-in-piazza-con-book-club-il-9-agosto%2F&amp;linkname=Cinema%20in%20piazza%20con%20%E2%80%9CBook%20Club%E2%80%9D%20il%209%20agosto\" title=\"Twitter\" target=\"_blank\" rel=\"noopener\"><\/a><a class=\"a2a_button_whatsapp\" href=\"https:\/\/www.addtoany.com\/add_to\/whatsapp?linkurl=https%3A%2F%2Fcassano.lavocedelpaese.info%2Findex.php%2F2023%2F08%2F07%2Fcinema-in-piazza-con-book-club-il-9-agosto%2F&amp;linkname=Cinema%20in%20piazza%20con%20%E2%80%9CBook%20Club%E2%80%9D%20il%209%20agosto\" title=\"WhatsApp\" target=\"_blank\" rel=\"noopener\"><\/a><a class=\"a2a_button_telegram\" href=\"https:\/\/www.addtoany.com\/add_to\/telegram?linkurl=https%3A%2F%2Fcassano.lavocedelpaese.info%2Findex.php%2F2023%2F08%2F07%2Fcinema-in-piazza-con-book-club-il-9-agosto%2F&amp;linkname=Cinema%20in%20piazza%20con%20%E2%80%9CBook%20Club%E2%80%9D%20il%209%20agosto\" title=\"Telegram\" target=\"_blank\" rel=\"noopener\"><\/a><a class=\"a2a_button_email\" href=\"https:\/\/www.addtoany.com\/add_to\/email?linkurl=https%3A%2F%2Fcassano.lavocedelpaese.info%2Findex.php%2F2023%2F08%2F07%2Fcinema-in-piazza-con-book-club-il-9-agosto%2F&amp;linkname=Cinema%20in%20piazza%20con%20%E2%80%9CBook%20Club%E2%80%9D%20il%209%20agosto\" title=\"Email\" target=\"_blank\" rel=\"noopener\"><\/a><\/p>\n<p>\u00a0<\/p>","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u200b\u00a0 \u200bCassano \u2013 La Voce del Paese\u00a0 Torna il cinema in piazza, per due serate, a Cassano delle Murge.<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1846","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/noicattaro.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts\/1846","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noicattaro.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noicattaro.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noicattaro.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/comments?post=1846"}],"version-history":[{"count":0,"href":"https:\/\/noicattaro.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts\/1846\/revisions"}],"wp:attachment":[{"href":"https:\/\/noicattaro.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/media?parent=1846"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noicattaro.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/categories?post=1846"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noicattaro.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/tags?post=1846"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}